{"id":476,"date":"2024-02-12T10:17:46","date_gmt":"2024-02-12T10:17:46","guid":{"rendered":"http:\/\/relox.de\/?page_id=177"},"modified":"2024-04-04T09:10:32","modified_gmt":"2024-04-04T09:10:32","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/relox.de\/de\/datenschutz\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"476\" class=\"elementor elementor-476\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-edeb4e8 e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"edeb4e8\" data-element_type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2269ac elementor-widget elementor-widget-heading\" data-id=\"d2269ac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Impressum<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d23170 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6d23170\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35dcb15 elementor-widget elementor-widget-text-editor\" data-id=\"35dcb15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Rene Niesner-Christe<br \/>Gesch\u00e4ftsf\u00fchrer<\/p><p>Westkai 62<br \/>27572 Bremerhaven<br \/>Deutschland<\/p><p><strong>Kontakt:<\/strong><br \/>Telefon: +49 471 3095 220<br \/>E-Mail: info@relox.de<\/p><p><strong>Registereintrag:<\/strong><br \/>Amtsgericht Bremen<br \/>Handelsregisternummer\u00a0HRB 24748 HB<\/p><p><strong>Umsatzsteuer-ID:<\/strong><br \/>Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a727a Umsatzsteuergesetz:<br \/>DE 259 014 387<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-166d1b3 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"166d1b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Datenschutzerkl\u00e4rung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c5a9ed elementor-hidden-desktop elementor-hidden-laptop elementor-widget elementor-widget-heading\" data-id=\"7c5a9ed\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Datenschutz-erkl\u00e4rung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fb3ca8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4fb3ca8\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2204f4 elementor-widget elementor-widget-text-editor\" data-id=\"a2204f4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 id=\"dsg-general-intro\">Diese Datenschutzerkl\u00e4rung kl\u00e4rt Sie \u00fcber die Art, den Umfang und Zweck der Verarbeitung von personenbezogenen Daten (nachfolgend kurz \u201eDaten\u201c) innerhalb unseres Onlineangebotes und der mit ihm verbundenen Webseiten, Funktionen und Inhalte sowie externen Onlinepr\u00e4senzen, wie z.B. unser Social Media Profile auf. (nachfolgend gemeinsam bezeichnet als \u201eOnlineangebot\u201c). Im Hinblick auf die verwendeten Begrifflichkeiten, wie z.B. \u201eVerarbeitung\u201c oder \u201eVerantwortlicher\u201c verweisen wir auf die Definitionen im Art. 4 der Datenschutzgrundverordnung (DSGVO).<\/h5>\n<h3 id=\"dsg-general-controller\"><strong>Verantwortlicher<\/strong><\/h3>\n<p><span class=\"tsmcontroller\">Rene Niesner-Christe<br>Gesch\u00e4ftsf\u00fchrer<\/span><\/p>\n<p>Westkai 62<br>27572 Bremerhaven<br>Deutschland<\/p>\n<p><strong>Kontakt:<\/strong><\/p>\n<p>Telefon: +49 471 3095 220<br>E-Mail: info@relox.de<\/p>\n<h3 id=\"dsg-general-datatype\"><strong>Arten der verarbeiteten Daten:<\/strong><\/h3>\n<p>\u2013 Bestandsdaten (z.B., Namen, Adressen).<br>\u2013 Kontaktdaten (z.B., E-Mail, Telefonnummern).<br>\u2013 Inhaltsdaten (z.B., Texteingaben, Fotografien, Videos).<br>\u2013 Nutzungsdaten (z.B., besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten).<br>\u2013 Meta-\/Kommunikationsdaten (z.B., Ger\u00e4te-Informationen, IP-Adressen).<\/p>\n<h3 id=\"dsg-general-purpose\"><strong>Zweck der Verarbeitung<\/strong><\/h3>\n<p>\u2013 Zurverf\u00fcgungstellung des Onlineangebotes, seiner Funktionen und Inhalte.<br>\u2013 Beantwortung von Kontaktanfragen und Kommunikation mit Nutzern.<br>\u2013 Sicherheitsma\u00dfnahmen.<br>\u2013 Reichweitenmessung\/Marketing<br><span class=\"tsmcom\">&nbsp;<\/span><\/p>\n<h3 id=\"dsg-general-terms\"><strong>Verwendete Begrifflichkeiten<\/strong><\/h3>\n<p>\u201ePersonenbezogene Daten\u201c sind alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person (im Folgenden \u201ebetroffene Person\u201c) beziehen; als identifizierbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung (z.B. Cookie) oder zu einem oder mehreren besonderen Merkmalen identifiziert werden kann, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind.<\/p>\n<p>\u201eVerarbeitung\u201c ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrten Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten. Der Begriff reicht weit und umfasst praktisch jeden Umgang mit Daten.<\/p>\n<p>Als \u201eVerantwortlicher\u201c wird die nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten entscheidet, bezeichnet.<\/p>\n<h3 id=\"dsg-general-legalbasis\"><strong>Ma\u00dfgebliche Rechtsgrundlagen<\/strong><\/h3>\n<p>Nach Ma\u00dfgabe des Art. 13 DSGVO teilen wir Ihnen die Rechtsgrundlagen unserer Datenverarbeitungen mit. Sofern die Rechtsgrundlage in der Datenschutzerkl\u00e4rung nicht genannt wird, gilt Folgendes: Die Rechtsgrundlage f\u00fcr die Einholung von Einwilligungen ist Art. 6 Abs. 1 lit. a und Art. 7 DSGVO, die Rechtsgrundlage f\u00fcr die Verarbeitung zur Erf\u00fcllung unserer Leistungen und Durchf\u00fchrung vertraglicher Ma\u00dfnahmen sowie Beantwortung von Anfragen ist Art. 6 Abs. 1 lit. b DSGVO, die Rechtsgrundlage f\u00fcr die Verarbeitung zur Erf\u00fcllung unserer rechtlichen Verpflichtungen ist Art. 6 Abs. 1 lit. c DSGVO, und die Rechtsgrundlage f\u00fcr die Verarbeitung zur Wahrung unserer berechtigten Interessen ist Art. 6 Abs. 1 lit. f DSGVO. F\u00fcr den Fall, dass lebenswichtige Interessen der betroffenen Person oder einer anderen nat\u00fcrlichen Person eine Verarbeitung personenbezogener Daten erforderlich machen, dient Art. 6 Abs. 1 lit. d DSGVO als Rechtsgrundlage.<\/p>\n<h3 id=\"dsg-general-securitymeasures\"><strong>Sicherheitsma\u00dfnahmen<\/strong><\/h3>\n<p>Wir bitten Sie sich regelm\u00e4\u00dfig \u00fcber den Inhalt unserer Datenschutzerkl\u00e4rung zu informieren. Wir passen die Datenschutzerkl\u00e4rung an, sobald die \u00c4nderungen der von uns durchgef\u00fchrten Datenverarbeitungen dies erforderlich machen. Wir informieren Sie, sobald durch die \u00c4nderungen eine Mitwirkungshandlung Ihrerseits (z.B. Einwilligung) oder eine sonstige individuelle Benachrichtigung erforderlich wird.<\/p>\n<h3 id=\"dsg-general-coprocessing\"><strong>Zusammenarbeit mit Auftragsverarbeitern und Dritten<\/strong><\/h3>\n<p>Sofern wir im Rahmen unserer Verarbeitung Daten gegen\u00fcber anderen Personen und Unternehmen (Auftragsverarbeitern oder Dritten) offenbaren, sie an diese \u00fcbermitteln oder ihnen sonst Zugriff auf die Daten gew\u00e4hren, erfolgt dies nur auf Grundlage einer gesetzlichen Erlaubnis (z.B. wenn eine \u00dcbermittlung der Daten an Dritte, wie an Zahlungsdienstleister, gem. Art. 6 Abs. 1 lit. b DSGVO zur Vertragserf\u00fcllung erforderlich ist), Sie eingewilligt haben, eine rechtliche Verpflichtung dies vorsieht oder auf Grundlage unserer berechtigten Interessen (z.B. beim Einsatz von Beauftragten, Webhostern, etc.).<\/p>\n<p>Sofern wir Dritte mit der Verarbeitung von Daten auf Grundlage eines sog. \u201eAuftragsverarbeitungsvertrages\u201c beauftragen, geschieht dies auf Grundlage des Art. 28 DSGVO.<\/p>\n<h3 id=\"dsg-general-thirdparty\"><strong>\u00dcbermittlungen in Drittl\u00e4nder<\/strong><\/h3>\n<p>Sofern wir Daten in einem Drittland (d.h. au\u00dferhalb der Europ\u00e4ischen Union (EU) oder des Europ\u00e4ischen Wirtschaftsraums (EWR)) verarbeiten oder dies im Rahmen der Inanspruchnahme von Diensten Dritter oder Offenlegung, bzw. \u00dcbermittlung von Daten an Dritte geschieht, erfolgt dies nur, wenn es zur Erf\u00fcllung unserer (vor)vertraglichen Pflichten, auf Grundlage Ihrer Einwilligung, aufgrund einer rechtlichen Verpflichtung oder auf Grundlage unserer berechtigten Interessen geschieht. Vorbehaltlich gesetzlicher oder vertraglicher Erlaubnisse, verarbeiten oder lassen wir die Daten in einem Drittland nur beim Vorliegen der besonderen Voraussetzungen der Art. 44 ff. DSGVO verarbeiten. D.h. die Verarbeitung erfolgt z.B. auf Grundlage besonderer Garantien, wie der offiziell anerkannten Feststellung eines der EU entsprechenden Datenschutzniveaus (z.B. f\u00fcr die USA durch das \u201ePrivacy Shield\u201c) oder Beachtung offiziell anerkannter spezieller vertraglicher Verpflichtungen (so genannte \u201eStandardvertragsklauseln\u201c).<\/p>\n<h3 id=\"dsg-general-rightssubject\"><strong>Rechte der betroffenen Personen<\/strong><\/h3>\n<p>Sie haben das Recht, eine Best\u00e4tigung dar\u00fcber zu verlangen, ob betreffende Daten verarbeitet werden und auf Auskunft \u00fcber diese Daten sowie auf weitere Informationen und Kopie der Daten entsprechend Art. 15 DSGVO.<\/p>\n<p>Sie haben entsprechend. Art. 16 DSGVO das Recht, die Vervollst\u00e4ndigung der Sie betreffenden Daten oder die Berichtigung der Sie betreffenden unrichtigen Daten zu verlangen.<\/p>\n<p>Sie haben nach Ma\u00dfgabe des Art. 17 DSGVO das Recht zu verlangen, dass betreffende Daten unverz\u00fcglich gel\u00f6scht werden, bzw. alternativ nach Ma\u00dfgabe des Art. 18 DSGVO eine Einschr\u00e4nkung der Verarbeitung der Daten zu verlangen.<\/p>\n<p>Sie haben das Recht zu verlangen, dass die Sie betreffenden Daten, die Sie uns bereitgestellt haben nach Ma\u00dfgabe des Art. 20 DSGVO zu erhalten und deren \u00dcbermittlung an andere Verantwortliche zu fordern.<\/p>\n<p>Sie haben ferner gem. Art. 77 DSGVO das Recht, eine Beschwerde bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde einzureichen.<\/p>\n<h3 id=\"dsg-general-revokeconsent\"><strong>Widerrufsrecht<\/strong><\/h3>\n<p>Sie haben das Recht, erteilte Einwilligungen gem. Art. 7 Abs. 3 DSGVO mit Wirkung f\u00fcr die Zukunft zu widerrufen.<\/p>\n<h3 id=\"dsg-general-object\"><strong>Widerspruchsrecht<\/strong><\/h3>\n<p>Sie k\u00f6nnen der k\u00fcnftigen Verarbeitung der Sie betreffenden Daten nach Ma\u00dfgabe des Art. 21 DSGVO jederzeit widersprechen. Der Widerspruch kann insbesondere gegen die Verarbeitung f\u00fcr Zwecke der Direktwerbung erfolgen.<\/p>\n<h3 id=\"dsg-general-cookies\"><strong>Cookies und Widerspruchsrecht bei Direktwerbung<\/strong><\/h3>\n<p>Als \u201eCookies\u201c werden kleine Dateien bezeichnet, die auf Rechnern der Nutzer gespeichert werden. Innerhalb der Cookies k\u00f6nnen unterschiedliche Angaben gespeichert werden. Ein Cookie dient prim\u00e4r dazu, die Angaben zu einem Nutzer (bzw. dem Ger\u00e4t auf dem das Cookie gespeichert ist) w\u00e4hrend oder auch nach seinem Besuch innerhalb eines Onlineangebotes zu speichern. Als tempor\u00e4re Cookies, bzw. \u201eSession-Cookies\u201c oder \u201etransiente Cookies\u201c, werden Cookies bezeichnet, die gel\u00f6scht werden, nachdem ein Nutzer ein Onlineangebot verl\u00e4sst und seinen Browser schlie\u00dft. In einem solchen Cookie kann z.B. der Inhalt eines Warenkorbs in einem Onlineshop oder ein Login-Staus gespeichert werden. Als \u201epermanent\u201c oder \u201epersistent\u201c werden Cookies bezeichnet, die auch nach dem Schlie\u00dfen des Browsers gespeichert bleiben. So kann z.B. der Login-Status gespeichert werden, wenn die Nutzer diese nach mehreren Tagen aufsuchen. Ebenso k\u00f6nnen in einem solchen Cookie die Interessen der Nutzer gespeichert werden, die f\u00fcr Reichweitenmessung oder Marketingzwecke verwendet werden. Als \u201eThird-Party-Cookie\u201c werden Cookies bezeichnet, die von anderen Anbietern als dem Verantwortlichen, der das Onlineangebot betreibt, angeboten werden (andernfalls, wenn es nur dessen Cookies sind spricht man von \u201eFirst-Party Cookies\u201c).<\/p>\n<p>Wir k\u00f6nnen tempor\u00e4re und permanente Cookies einsetzen und kl\u00e4ren hier\u00fcber im Rahmen unserer Datenschutzerkl\u00e4rung auf.<\/p>\n<p>Falls die Nutzer nicht m\u00f6chten, dass Cookies auf ihrem Rechner gespeichert werden, werden sie gebeten die entsprechende Option in den Systemeinstellungen ihres Browsers zu deaktivieren. Gespeicherte Cookies k\u00f6nnen in den Systemeinstellungen des Browsers gel\u00f6scht werden. Der Ausschluss von Cookies kann zu Funktionseinschr\u00e4nkungen dieses Onlineangebotes f\u00fchren.<\/p>\n<p>Ein genereller Widerspruch gegen den Einsatz der zu Zwecken des Onlinemarketing eingesetzten Cookies kann bei einer Vielzahl der Dienste, vor allem im Fall des Trackings, \u00fcber die US-amerikanische Seite&nbsp;<\/p>\n<p><a href=\"http:\/\/www.aboutads.info\/choices\/\">http:\/\/www.aboutads.info\/choices\/<\/a><\/p>\n<p>&nbsp;oder die EU-Seite&nbsp;<\/p>\n<p><a href=\"http:\/\/www.youronlinechoices.com\/\">http:\/\/www.youronlinechoices.com\/<\/a><\/p>\n<p>&nbsp;erkl\u00e4rt werden. Des Weiteren kann die Speicherung von Cookies mittels deren Abschaltung in den Einstellungen des Browsers erreicht werden. Bitte beachten Sie, dass dann gegebenenfalls nicht alle Funktionen dieses Onlineangebotes genutzt werden k\u00f6nnen.<\/p>\n<h3 id=\"dsg-general-erasure\"><strong>L\u00f6schung von Daten<\/strong><\/h3>\n<p>Die von uns verarbeiteten Daten werden nach Ma\u00dfgabe der Art. 17 und 18 DSGVO gel\u00f6scht oder in ihrer Verarbeitung eingeschr\u00e4nkt. Sofern nicht im Rahmen dieser Datenschutzerkl\u00e4rung ausdr\u00fccklich angegeben, werden die bei uns gespeicherten Daten gel\u00f6scht, sobald sie f\u00fcr ihre Zweckbestimmung nicht mehr erforderlich sind und der L\u00f6schung keine gesetzlichen Aufbewahrungspflichten entgegenstehen. Sofern die Daten nicht gel\u00f6scht werden, weil sie f\u00fcr andere und gesetzlich zul\u00e4ssige Zwecke erforderlich sind, wird deren Verarbeitung eingeschr\u00e4nkt. D.h. die Daten werden gesperrt und nicht f\u00fcr andere Zwecke verarbeitet. Das gilt z.B. f\u00fcr Daten, die aus handels- oder steuerrechtlichen Gr\u00fcnden aufbewahrt werden m\u00fcssen.<\/p>\n<p>Nach gesetzlichen Vorgaben in Deutschland erfolgt die Aufbewahrung insbesondere f\u00fcr 6 Jahre gem\u00e4\u00df \u00a7 257 Abs. 1 HGB (Handelsb\u00fccher, Inventare, Er\u00f6ffnungsbilanzen, Jahresabschl\u00fcsse, Handelsbriefe, Buchungsbelege, etc.) sowie f\u00fcr 10 Jahre gem\u00e4\u00df \u00a7 147 Abs. 1 AO (B\u00fccher, Aufzeichnungen, Lageberichte, Buchungsbelege, Handels- und Gesch\u00e4ftsbriefe, F\u00fcr Besteuerung relevante Unterlagen, etc.).<\/p>\n<p>Nach gesetzlichen Vorgaben in \u00d6sterreich erfolgt die Aufbewahrung insbesondere f\u00fcr 7 J gem\u00e4\u00df \u00a7 132 Abs. 1 BAO (Buchhaltungsunterlagen, Belege\/Rechnungen, Konten, Belege, Gesch\u00e4ftspapiere, Aufstellung der Einnahmen und Ausgaben, etc.), f\u00fcr 22 Jahre im Zusammenhang mit Grundst\u00fccken und f\u00fcr 10 Jahre bei Unterlagen im Zusammenhang mit elektronisch erbrachten Leistungen, Telekommunikations-, Rundfunk- und Fernsehleistungen, die an Nichtunternehmer in EU-Mitgliedstaaten erbracht werden und f\u00fcr die der Mini-One-Stop-Shop (MOSS) in Anspruch genommen wird.<\/p>\n<h3 id=\"dsg-hostingprovider\"><strong>Hosting<\/strong><\/h3>\n<p><span class=\"ts-muster-content\">Die von uns in Anspruch genommenen Hosting-Leistungen dienen der Zurverf\u00fcgungstellung der folgenden Leistungen: Infrastruktur- und Plattformdienstleistungen, Rechenkapazit\u00e4t, Speicherplatz und Datenbankdienste, Sicherheitsleistungen sowie technische Wartungsleistungen, die wir zum Zwecke des Betriebs dieses Onlineangebotes einsetzen.<\/span><\/p>\n<p>Hierbei verarbeiten wir, bzw. unser Hostinganbieter Bestandsdaten, Kontaktdaten, Inhaltsdaten, Vertragsdaten, Nutzungsdaten, Meta- und Kommunikationsdaten von Kunden, Interessenten und Besuchern dieses Onlineangebotes auf Grundlage unserer berechtigten Interessen an einer effizienten und sicheren Zurverf\u00fcgungstellung dieses Onlineangebotes gem. Art. 6 Abs. 1 lit. f DSGVO i.V.m. Art. 28 DSGVO (Abschluss Auftragsverarbeitungsvertrag).<\/p>\n<h3 id=\"dsg-logfiles\"><strong>Erhebung von Zugriffsdaten und Logfiles<\/strong><\/h3>\n<p><span class=\"ts-muster-content\">Wir, bzw. unser Hostinganbieter, erhebt auf Grundlage unserer berechtigten Interessen im Sinne des Art. 6 Abs. 1 lit. f. DSGVO Daten \u00fcber jeden Zugriff auf den Server, auf dem sich dieser Dienst befindet (sogenannte Serverlogfiles). Zu den Zugriffsdaten geh\u00f6ren Name der abgerufenen Webseite, Datei, Datum und Uhrzeit des Abrufs, \u00fcbertragene Datenmenge, Meldung \u00fcber erfolgreichen Abruf, Browsertyp nebst Version, das Betriebssystem des Nutzers, Referrer URL (die zuvor besuchte Seite), IP-Adresse und der anfragende Provider.<\/span><\/p>\n<p>Logfile-Informationen werden aus Sicherheitsgr\u00fcnden (z.B. zur Aufkl\u00e4rung von Missbrauchs- oder Betrugshandlungen) f\u00fcr die Dauer von maximal 7 Tagen gespeichert und danach gel\u00f6scht. Daten, deren weitere Aufbewahrung zu Beweiszwecken erforderlich ist, sind bis zur endg\u00fcltigen Kl\u00e4rung des jeweiligen Vorfalls von der L\u00f6schung ausgenommen.<\/p>\n<h3 id=\"dsg-services-contractualservices\"><strong>Erbringung vertraglicher Leistungen<\/strong><\/h3>\n<p><span class=\"ts-muster-content\">Wir verarbeiten Bestandsdaten (z.B., Namen und Adressen sowie Kontaktdaten von Nutzern), Vertragsdaten (z.B., in Anspruch genommene Leistungen, Namen von Kontaktpersonen, Zahlungsinformationen) zwecks Erf\u00fcllung unserer vertraglichen Verpflichtungen und Serviceleistungen gem. Art. 6 Abs. 1 lit b. DSGVO. Die in Onlineformularen als verpflichtend gekennzeichneten Eingaben, sind f\u00fcr den Vertragsschluss erforderlich.<\/span><\/p>\n<p>Im Rahmen der Inanspruchnahme unserer Onlinedienste, speichern wir die IP-Adresse und den Zeitpunkt der jeweiligen Nutzerhandlung. Die Speicherung erfolgt auf Grundlage unserer berechtigten Interessen, als auch der Nutzer an Schutz vor Missbrauch und sonstiger unbefugter Nutzung. Eine Weitergabe dieser Daten an Dritte erfolgt grunds\u00e4tzlich nicht, au\u00dfer sie ist zur Verfolgung unserer Anspr\u00fcche erforderlich oder es besteht hierzu eine gesetzliche Verpflichtung gem. Art. 6 Abs. 1 lit. c DSGVO.<\/p>\n<p>Wir verarbeiten Nutzungsdaten (z.B., die besuchten Webseiten unseres Onlineangebotes, Interesse an unseren Produkten) und Inhaltsdaten (z.B., Eingaben im Kontaktformular oder Nutzerprofil) f\u00fcr Werbezwecke in einem Nutzerprofil, um den Nutzer z.B. Produkthinweise ausgehend von ihren bisher in Anspruch genommenen Leistungen einzublenden.<\/p>\n<p>Die L\u00f6schung der Daten erfolgt nach Ablauf gesetzlicher Gew\u00e4hrleistungs- und vergleichbarer Pflichten, die Erforderlichkeit der Aufbewahrung der Daten wird alle drei Jahre \u00fcberpr\u00fcft; im Fall der gesetzlichen Archivierungspflichten erfolgt die L\u00f6schung nach deren Ablauf. Angaben im etwaigen Kundenkonto verbleiben bis zu dessen L\u00f6schung.<\/p>\n<h3 id=\"dsg-administration\"><strong>Administration, Finanzbuchhaltung, B\u00fcroorganisation, Kontaktverwaltung<\/strong><\/h3>\n<p><span class=\"ts-muster-content\">Wir verarbeiten Daten im Rahmen von Verwaltungsaufgaben sowie Organisation unseres Betriebs, Finanzbuchhaltung und Befolgung der gesetzlichen Pflichten, wie z.B. der Archivierung. Herbei verarbeiten wir dieselben Daten, die wir im Rahmen der Erbringung unserer vertraglichen Leistungen verarbeiten. Die Verarbeitungsgrundlagen sind Art. 6 Abs. 1 lit. c. DSGVO, Art. 6 Abs. 1 lit. f. DSGVO. Von der Verarbeitung sind Kunden, Interessenten, Gesch\u00e4ftspartner und Websitebesucher betroffen. Der Zweck und unser Interesse an der Verarbeitung liegt in der Administration, Finanzbuchhaltung, B\u00fcroorganisation, Archivierung von Daten, also Aufgaben die der Aufrechterhaltung unserer Gesch\u00e4ftst\u00e4tigkeiten, Wahrnehmung unserer Aufgaben und Erbringung unserer Leistungen dienen. Die L\u00f6schung der Daten im Hinblick auf vertragliche Leistungen und die vertragliche Kommunikation entspricht den, bei diesen Verarbeitungst\u00e4tigkeiten genannten Angaben.<\/span><\/p>\n<p>Wir offenbaren oder \u00fcbermitteln hierbei Daten an die Finanzverwaltung, Berater, wie z.B., Steuerberater oder Wirtschaftspr\u00fcfer sowie weitere Geb\u00fchrenstellen und Zahlungsdienstleister.<\/p>\n<p>Ferner speichern wir auf Grundlage unserer betriebswirtschaftlichen Interessen Angaben zu Lieferanten, Veranstaltern und sonstigen Gesch\u00e4ftspartnern, z.B. zwecks sp\u00e4terer Kontaktaufnahme. Diese mehrheitlich unternehmensbezogenen Daten, speichern wir grunds\u00e4tzlich dauerhaft.<\/p>\n<h3 id=\"dsg-contact\"><strong>Kontaktaufnahme<\/strong><\/h3>\n<p><span class=\"ts-muster-content\">Bei der Kontaktaufnahme mit uns (z.B. per Kontaktformular, E-Mail, Telefon oder via sozialer Medien) werden die Angaben des Nutzers zur Bearbeitung der Kontaktanfrage und deren Abwicklung gem. Art. 6 Abs. 1 lit. b) DSGVO verarbeitet. Die Angaben der Nutzer k\u00f6nnen in einem Customer-Relationship-Management System (\u201eCRM System\u201c) oder vergleichbarer Anfragenorganisation gespeichert werden.<\/span><\/p>\n<p>Wir l\u00f6schen die Anfragen, sofern diese nicht mehr erforderlich sind. Wir \u00fcberpr\u00fcfen die Erforderlichkeit alle zwei Jahre; Ferner gelten die gesetzlichen Archivierungspflichten.<\/p>\n<h3 id=\"dsg-googleanalytics\"><strong>Google Analytics<\/strong><\/h3>\n<p><span class=\"ts-muster-content\">Wir setzen auf Grundlage unserer berechtigten Interessen (d.h. Interesse an der Analyse, Optimierung und wirtschaftlichem Betrieb unseres Onlineangebotes im Sinne des Art. 6 Abs. 1 lit. f. DSGVO) Google Analytics, einen Webanalysedienst der Google LLC (\u201eGoogle\u201c) ein. Google verwendet Cookies. Die durch das Cookie erzeugten Informationen \u00fcber Benutzung des Onlineangebotes durch die Nutzer werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert.<\/span><\/p>\n<p>Google ist unter dem Privacy-Shield-Abkommen zertifiziert und bietet hierdurch eine Garantie, das europ\u00e4ische Datenschutzrecht einzuhalten&nbsp;<\/p>\n<p>(<a href=\"https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI&amp;status=Active\" target=\"_blank\" rel=\"noopener\">https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI&amp;status=Active<\/a>).<\/p>\n<p>Google wird diese Informationen in unserem Auftrag benutzen, um die Nutzung unseres Onlineangebotes durch die Nutzer auszuwerten, um Reports \u00fcber die Aktivit\u00e4ten innerhalb dieses Onlineangebotes zusammenzustellen und um weitere, mit der Nutzung dieses Onlineangebotes und der Internetnutzung verbundene Dienstleistungen, uns gegen\u00fcber zu erbringen. Dabei k\u00f6nnen aus den verarbeiteten Daten pseudonyme Nutzungsprofile der Nutzer erstellt werden.<\/p>\n<p>Wir setzen Google Analytics nur mit aktivierter IP-Anonymisierung ein. Das bedeutet, die IP-Adresse der Nutzer wird von Google innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt.<\/p>\n<p>Die von dem Browser des Nutzers \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt. Die Nutzer k\u00f6nnen die Speicherung der Cookies durch eine entsprechende Einstellung ihrer Browser-Software verhindern; die Nutzer k\u00f6nnen dar\u00fcber hinaus die Erfassung der durch das Cookie erzeugten und auf ihre Nutzung des Onlineangebotes bezogenen Daten an Google sowie die Verarbeitung dieser Daten durch Google verhindern, indem sie das unter folgendem Link verf\u00fcgbare Browser-Plugin herunterladen und installieren:&nbsp;<\/p>\n<p><a href=\"http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener\">http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>.<\/p>\n<p>Weitere Informationen zur Datennutzung durch Google, Einstellungs- und Widerspruchsm\u00f6glichkeiten, erfahren Sie in der Datenschutzerkl\u00e4rung von Google&nbsp;<\/p>\n<p>(<a href=\"https:\/\/policies.google.com\/technologies\/ads\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/technologies\/ads<\/a>)&nbsp;<\/p>\n<p>sowie in den Einstellungen f\u00fcr die Darstellung von Werbeeinblendungen durch Google&nbsp;<\/p>\n<p><a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noopener\">(https:\/\/adssettings.google.com\/authenticated<\/a>).<\/p>\n<p>Die personenbezogenen Daten der Nutzer werden nach 14 Monaten gel\u00f6scht oder anonymisert.<\/p>\n<h3 id=\"dsg-socialmedia\"><strong>Onlinepr\u00e4senzen in sozialen Medien<\/strong><\/h3>\n<p><span class=\"ts-muster-content\">Wir unterhalten Onlinepr\u00e4senzen innerhalb sozialer Netzwerke und Plattformen, um mit den dort aktiven Kunden, Interessenten und Nutzern kommunizieren und sie dort \u00fcber unsere Leistungen informieren zu k\u00f6nnen. Beim Aufruf der jeweiligen Netzwerke und Plattformen gelten die Gesch\u00e4ftsbedingungen und die Datenverarbeitungsrichtlinien deren jeweiligen Betreiber.<\/span><\/p>\n<p>Soweit nicht anders im Rahmen unserer Datenschutzerkl\u00e4rung angegeben, verarbeiten wir die Daten der Nutzer sofern diese mit uns innerhalb der sozialen Netzwerke und Plattformen kommunizieren, z.B. Beitr\u00e4ge auf unseren Onlinepr\u00e4senzen verfassen oder uns Nachrichten zusenden.<\/p>\n<h3 id=\"dsg-thirdparty-einleitung\"><strong>Einbindung von Diensten und Inhalten Dritter<\/strong><\/h3>\n<p><span class=\"ts-muster-content\">Wir setzen innerhalb unseres Onlineangebotes auf Grundlage unserer berechtigten Interessen (d.h. Interesse an der Analyse, Optimierung und wirtschaftlichem Betrieb unseres Onlineangebotes im Sinne des Art. 6 Abs. 1 lit. f. DSGVO) Inhalts- oder Serviceangebote von Drittanbietern ein, um deren Inhalte und Services, wie z.B. Videos oder Schriftarten einzubinden (nachfolgend einheitlich bezeichnet als \u201cInhalte\u201d).<\/span><\/p>\n<p>Dies setzt immer voraus, dass die Drittanbieter dieser Inhalte, die IP-Adresse der Nutzer wahrnehmen, da sie ohne die IP-Adresse die Inhalte nicht an deren Browser senden k\u00f6nnten. Die IP-Adresse ist damit f\u00fcr die Darstellung dieser Inhalte erforderlich. Wir bem\u00fchen uns nur solche Inhalte zu verwenden, deren jeweilige Anbieter die IP-Adresse lediglich zur Auslieferung der Inhalte verwenden. Drittanbieter k\u00f6nnen ferner so genannte Pixel-Tags (unsichtbare Grafiken, auch als \u201eWeb Beacons\u201c bezeichnet) f\u00fcr statistische oder Marketingzwecke verwenden. Durch die \u201ePixel-Tags\u201c k\u00f6nnen Informationen, wie der Besucherverkehr auf den Seiten dieser Website ausgewertet werden. Die pseudonymen Informationen k\u00f6nnen ferner in Cookies auf dem Ger\u00e4t der Nutzer gespeichert werden und unter anderem technische Informationen zum Browser und Betriebssystem, verweisende Webseiten, Besuchszeit sowie weitere Angaben zur Nutzung unseres Onlineangebotes enthalten, als auch mit solchen Informationen aus anderen Quellen verbunden werden.<\/p>\n<h3 id=\"dsg-thirdparty-youtube\"><strong>Youtube<\/strong><\/h3>\n<p><span class=\"ts-muster-content\">Wir binden die Videos der Plattform \u201cYouTube\u201d des Anbieters Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA, ein. Datenschutzerkl\u00e4rung:&nbsp;<\/span><\/p>\n<p><span class=\"ts-muster-content\"><a href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com\/policies\/privacy\/<\/a>,&nbsp;<\/span><\/p>\n<p><span class=\"ts-muster-content\">Opt-Out:&nbsp;<\/span><\/p>\n<p><span class=\"ts-muster-content\"><a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noopener\">https:\/\/adssettings.google.com\/authenticated<\/a>.<\/span><\/p>\n<h3 id=\"dsg-thirdparty-googlemaps\"><strong>Google Maps<\/strong><\/h3>\n<p><span class=\"ts-muster-content\">Wir binden die Landkarten des Dienstes \u201cGoogle Maps\u201d des Anbieters Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA, ein. Zu den verarbeiteten Daten k\u00f6nnen insbesondere IP-Adressen und Standortdaten der Nutzer geh\u00f6ren, die jedoch nicht ohne deren Einwilligung (im Regelfall im Rahmen der Einstellungen ihrer Mobilger\u00e4te vollzogen), erhoben werden. Die Daten k\u00f6nnen in den USA verarbeitet werden. Datenschutzerkl\u00e4rung:&nbsp;<\/span><\/p>\n<p><span class=\"ts-muster-content\"><a href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com\/policies\/privacy\/<\/a>,&nbsp;<\/span><\/p>\n<p><span class=\"ts-muster-content\">Opt-Out:&nbsp;<\/span><\/p>\n<p><span class=\"ts-muster-content\"><a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noopener\">https:\/\/adssettings.google.com\/authenticated<\/a>.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Impressum Rene Niesner-ChristeGesch\u00e4ftsf\u00fchrer Westkai 6227572 BremerhavenDeutschland Kontakt:Telefon: +49 471 3095 220E-Mail: info@relox.de Registereintrag:Amtsgericht BremenHandelsregisternummer\u00a0HRB 24748 HB Umsatzsteuer-ID:Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a727a Umsatzsteuergesetz:DE 259 014 387 Datenschutzerkl\u00e4rung Datenschutz-erkl\u00e4rung Diese Datenschutzerkl\u00e4rung kl\u00e4rt Sie \u00fcber die Art, den Umfang und Zweck der Verarbeitung von personenbezogenen Daten (nachfolgend kurz \u201eDaten\u201c) innerhalb unseres Onlineangebotes und der mit ihm verbundenen Webseiten, Funktionen und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutz - RELOX GRUPPE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/relox.de\/de\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz - RELOX GRUPPE\" \/>\n<meta property=\"og:description\" content=\"Impressum Rene Niesner-ChristeGesch\u00e4ftsf\u00fchrer Westkai 6227572 BremerhavenDeutschland Kontakt:Telefon: +49 471 3095 220E-Mail: info@relox.de Registereintrag:Amtsgericht BremenHandelsregisternummer\u00a0HRB 24748 HB Umsatzsteuer-ID:Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a727a Umsatzsteuergesetz:DE 259 014 387 Datenschutzerkl\u00e4rung Datenschutz-erkl\u00e4rung Diese Datenschutzerkl\u00e4rung kl\u00e4rt Sie \u00fcber die Art, den Umfang und Zweck der Verarbeitung von personenbezogenen Daten (nachfolgend kurz \u201eDaten\u201c) innerhalb unseres Onlineangebotes und der mit ihm verbundenen Webseiten, Funktionen und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/relox.de\/de\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"RELOX GRUPPE\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-04T09:10:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/relox.de\/datenschutz\/\",\"url\":\"https:\/\/relox.de\/datenschutz\/\",\"name\":\"Datenschutz - RELOX GRUPPE\",\"isPartOf\":{\"@id\":\"https:\/\/relox.de\/de\/#website\"},\"datePublished\":\"2024-02-12T10:17:46+00:00\",\"dateModified\":\"2024-04-04T09:10:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/relox.de\/datenschutz\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/relox.de\/datenschutz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/relox.de\/datenschutz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/relox.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/relox.de\/de\/#website\",\"url\":\"https:\/\/relox.de\/de\/\",\"name\":\"RELOX GRUPPE\",\"description\":\"Ihr Gewinn durch unsere Technik\",\"publisher\":{\"@id\":\"https:\/\/relox.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/relox.de\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/relox.de\/de\/#organization\",\"name\":\"RELOX AG\",\"url\":\"https:\/\/relox.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/relox.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/relox.de\/wp-content\/uploads\/2024\/02\/cropped-relox-logogo.png\",\"contentUrl\":\"http:\/\/relox.de\/wp-content\/uploads\/2024\/02\/cropped-relox-logogo.png\",\"width\":512,\"height\":512,\"caption\":\"RELOX AG\"},\"image\":{\"@id\":\"https:\/\/relox.de\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz - RELOX GRUPPE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/relox.de\/de\/datenschutz\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutz - RELOX GRUPPE","og_description":"Impressum Rene Niesner-ChristeGesch\u00e4ftsf\u00fchrer Westkai 6227572 BremerhavenDeutschland Kontakt:Telefon: +49 471 3095 220E-Mail: info@relox.de Registereintrag:Amtsgericht BremenHandelsregisternummer\u00a0HRB 24748 HB Umsatzsteuer-ID:Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a727a Umsatzsteuergesetz:DE 259 014 387 Datenschutzerkl\u00e4rung Datenschutz-erkl\u00e4rung Diese Datenschutzerkl\u00e4rung kl\u00e4rt Sie \u00fcber die Art, den Umfang und Zweck der Verarbeitung von personenbezogenen Daten (nachfolgend kurz \u201eDaten\u201c) innerhalb unseres Onlineangebotes und der mit ihm verbundenen Webseiten, Funktionen und [&hellip;]","og_url":"https:\/\/relox.de\/de\/datenschutz\/","og_site_name":"RELOX GRUPPE","article_modified_time":"2024-04-04T09:10:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"16 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/relox.de\/datenschutz\/","url":"https:\/\/relox.de\/datenschutz\/","name":"Datenschutz - RELOX GRUPPE","isPartOf":{"@id":"https:\/\/relox.de\/de\/#website"},"datePublished":"2024-02-12T10:17:46+00:00","dateModified":"2024-04-04T09:10:32+00:00","breadcrumb":{"@id":"https:\/\/relox.de\/datenschutz\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/relox.de\/datenschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/relox.de\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/relox.de\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/relox.de\/de\/#website","url":"https:\/\/relox.de\/de\/","name":"RELOX GRUPPE","description":"Ihr Gewinn durch unsere Technik","publisher":{"@id":"https:\/\/relox.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/relox.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/relox.de\/de\/#organization","name":"RELOX AG","url":"https:\/\/relox.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/relox.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/relox.de\/wp-content\/uploads\/2024\/02\/cropped-relox-logogo.png","contentUrl":"http:\/\/relox.de\/wp-content\/uploads\/2024\/02\/cropped-relox-logogo.png","width":512,"height":512,"caption":"RELOX AG"},"image":{"@id":"https:\/\/relox.de\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/relox.de\/de\/wp-json\/wp\/v2\/pages\/476"}],"collection":[{"href":"https:\/\/relox.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/relox.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/relox.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/relox.de\/de\/wp-json\/wp\/v2\/comments?post=476"}],"version-history":[{"count":69,"href":"https:\/\/relox.de\/de\/wp-json\/wp\/v2\/pages\/476\/revisions"}],"predecessor-version":[{"id":2758,"href":"https:\/\/relox.de\/de\/wp-json\/wp\/v2\/pages\/476\/revisions\/2758"}],"wp:attachment":[{"href":"https:\/\/relox.de\/de\/wp-json\/wp\/v2\/media?parent=476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}